{"id":6260,"date":"2018-05-24T08:00:41","date_gmt":"2018-05-24T06:00:41","guid":{"rendered":"https:\/\/www.elcornetin.es\/blog\/?p=6260"},"modified":"2021-09-22T21:32:26","modified_gmt":"2021-09-22T19:32:26","slug":"resena-gretchinz-injuztaz-karreraz-de-kanijoz","status":"publish","type":"post","link":"https:\/\/www.elcornetin.es\/blog\/juegos\/resena-gretchinz-injuztaz-karreraz-de-kanijoz\/","title":{"rendered":"[Rese\u00f1a] Gretchinz: Injuztaz Karreraz de Kanijoz"},"content":{"rendered":"<p>Games Workshop ha apostado por la renovaci\u00f3n, tanto de juegos como de tem\u00e1ticas, tras la publicaci\u00f3n de la 8\u00ba edici\u00f3n. Como parte de esta renovaci\u00f3n han comenzado a aparecer los primeros juegos de mesas de editoriales ajenas a GW. Uno de ellos es el sorprende<strong> Gretchinz de Devir<\/strong>.<!--more--><\/p>\n<p><strong>Conseguir<\/strong> <strong>una licencia de Warhammer 4000<\/strong>\u00a0para hacer un juego (WH40K) <strong>no es f\u00e1cil<\/strong>. Games Workshop (GW) mira con lupa cada propuesta que le llega y las que conceden debe cumplir condiciones muy claras. Por ello <strong>cuando Devir anuncio Gretchinz<\/strong>, luciendo el logo de WH40K en su portada, no solo anunci\u00f3 <strong>un gran juego<\/strong>, tambi\u00e9n anunci\u00f3 el \u00e9xito que supone haberlo conseguido. No he podido resistirme y antes de comenzar a contaros el juego el dejo un <strong>breve relato<\/strong> sobre uno de mis personajes de favoritos de <strong>Gorka Morka, el Gran Gretchin Rojo<\/strong>, valeroso l\u00edder del\u00a0Komite Revoluzionario Gretchin (KRG)<\/p>\n<figure id=\"attachment_6316\" aria-describedby=\"caption-attachment-6316\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.elcornetin.es\/blog\/juegos\/resena-gretchinz-injuztaz-karreraz-de-kanijoz\/\"><img decoding=\"async\" class=\"wp-image-6316 size-large lazyload\" data-src=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-1024x739.png\" alt=\"\" width=\"1024\" height=\"739\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-1024x739.png 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-300x217.png 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-768x554.png 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-150x108.png 150w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo-500x361.png 500w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/granGretchinRojo.png 1064w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/739;\" \/><\/a><figcaption id=\"caption-attachment-6316\" class=\"wp-caption-text\">Gran Gretchin Rojo, carism\u00e1tico l\u00edder del KRG<\/figcaption><\/figure>\n<h6>\u00abUn d\u00eda en las karreraz\u00bb<\/h6>\n<p>El sol abrasaba el \u201cGran Zokav\u00f3n\u201d mientras los ruidosos equipos de gretchinz empujaban los destartalados buggys a la l\u00ednea \u00bfrecta?, que un est\u00fapido snotling marcaba en el suelo con el pie. Ah\u00ed estaban Zyg , \u201cMarcha atraz\u201d, que hab\u00eda corrido su primera carrera haciendo honor a su nombre; \u201cGraziento\u201d Dekki, con la misma cantidad de ro\u00f1a que su buggy; Grot, \u201cManoz Firmez\u201d que hab\u00eda conseguido ir recto durante \u00abmuchos\u00bb metros; y \u00abKuvo\u00bb, un kanijo tan est\u00fapido que a\u00fan no se hab\u00eda ganado el mote .<\/p>\n<p>El Gran Gretchin Rojo, con su disfraz de morkista, tiraba de la cadena de los los garrapatoz zabuezoz, que proteg\u00edan el buggy que el KRG hab\u00eda fabricado con piezas de desecho. Escup\u00eda \u00f3rdenes con su voz chillona al resto de kanijos de su equipo. Ganar\u00eda la carrera, y cuando cruzara la meta, revelar\u00eda qui\u00e9n era. Entonces el resto de Gretchiz se levantar\u00edan contra sus amos Orkos. Nada pod\u00eda fallar, todo estaba controlado, todo menos que uno de los garrapatoz zabuezos se le tragara la mano de conducir, mientras intentaba sacarlo del buggy.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-6307 lazyload\" data-src=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchinz00.jpg\" alt=\"\" width=\"650\" height=\"389\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchinz00.jpg 650w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchinz00-300x180.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchinz00-150x90.jpg 150w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchinz00-500x299.jpg 500w\" data-sizes=\"(max-width: 650px) 100vw, 650px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 650px; --smush-placeholder-aspect-ratio: 650\/389;\" \/><\/p>\n<h6>\u00bfDe qu\u00e9 va el juego de Gretchinz?<\/h6>\n<p>Los <strong>Orks son una especie brutal y salvaje que viven por y para el combate y las emociones fuertes<\/strong>, un peligro para todas las dem\u00e1s razas del 40\u00ba Milenio. Una sociedad de brutales guerreros que se apoyan en los <strong>Gretchinz,\u00a0 astutas y malvadas criaturas que les sirven como esclavos<\/strong>. Las raras ocasiones que los Orks no est\u00e1n peleando buscan su raci\u00f3n de violencia en otras actividades, \u00bfy qu\u00e9 mejor una buena pelea tras las apuestas de una \u201cKarrera de Kanijoz\u201d?\u00a0<strong>Con unos destartalados buggies<\/strong>, construidos con las piezas que consiguen robar a los \u201cMeks\u201d,<strong> los Gretchinz se lanzan a una violenta y ca\u00f3tica carrera a trav\u00e9s de una planicie<\/strong>. Para ganar todo vale: juego sucio, armas, explosiones o sabotear al rival, solo acu\u00e9rdate de frenar al pasar la linea de meta.<\/p>\n<figure id=\"attachment_6310\" aria-describedby=\"caption-attachment-6310\" style=\"width: 443px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-6310 size-full lazyload\" data-src=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz01.jpg\" alt=\"\" width=\"443\" height=\"472\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz01.jpg 443w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz01-282x300.jpg 282w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz01-150x160.jpg 150w\" data-sizes=\"(max-width: 443px) 100vw, 443px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 443px; --smush-placeholder-aspect-ratio: 443\/472;\" \/><figcaption id=\"caption-attachment-6310\" class=\"wp-caption-text\">Componentes del juego<\/figcaption><\/figure>\n<h6>El juego.<\/h6>\n<p><strong>Gretchinz!<\/strong>, en palabras de su creador, Roberto Fraga, <strong>es una mezcla de Mad Max con Mario Kart; es injusto, es ca\u00f3tico y es r\u00e1pido<\/strong>, y todo ello recrea perfectamente la el trasfondo Ork del WH40K. <strong>Es injusto<\/strong>, porque por muy bien que lo hagas posiblemente tu arma falle, no consigas esquivar el \u201czokabon\u201d o tus compa\u00f1eros fijen sus miras en ti por una cosa tan simple como ir por delante. <strong>Es ca\u00f3tico<\/strong>, porque el ruido de los dados sirve para dar paso a un gran grito de \u201cwaagggh\u201d, porque ir en l\u00ednea recta es un sue\u00f1o en un tablero que se descubre cada vez que avanza un buggie. Y <strong>es r\u00e1pido<\/strong>, porque hay pocos juegos en que los que la duraci\u00f3n de la partida pueda ser menor que la propuesta en la caja.<\/p>\n<p><strong>\u00bfCosas que se podr\u00edan mejorarse en el juego?<\/strong> <strong>Las cartas<\/strong>, aunque <strong>las ilustraciones corren al cargo de Albert Monteys<\/strong>, lo cierto es que <strong>parecen muy uniformeS<\/strong> y con un primer vistazo puede no ser suficiente para hacerte la idea de la mejor ruta a tomar. El segundo punto <strong>a mejorar son los buggys<\/strong>; por petici\u00f3n de GW sus juegos no pueden tener miniaturas, por lo que hacer una figura de troquel de cart\u00f3n es una buena soluci\u00f3n, lo malo es que <strong>su montaje es dif\u00edcil y sin instrucciones<\/strong> debes tirar de intuici\u00f3n y debe hacerse con cuidado.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-6314 lazyload\" data-src=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-1024x314.jpg\" alt=\"\" width=\"1024\" height=\"314\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-1024x314.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-300x92.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-768x236.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-150x46.jpg 150w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03-500x153.jpg 500w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/gretchintz03.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/314;\" \/><\/p>\n<p>Gretchinz es uno de esos <strong>juegos con reglas sencillas, a los que te enganchas con facilidad.<\/strong> Cada jugador se alinear\u00e1 en la salida y su mostrando la primera fila de terreno. Despu\u00e9s de ello,\u00a0<strong>los jugadores empezar\u00e1n a lanzar sus dados y a quedarse con los resultados que deseen<\/strong>, cuando un jugador este contento con su resultado y haya colocado sus dados en su ficha, gritara \u201c<strong>Waaaagh\u201d indicando que no se pueden hacer m\u00e1s tiradas<\/strong>. Empezando por el jugador que lanzo el grito se resuelven las <strong>acciones en los dados<\/strong>: avanzar por el desierto, jugar la acci\u00f3n especial del Klan Orko o atacar, cosa que no siempre sale bien pues no sabes que cartas de ataque tienes. <strong>El ganador es el primer jugador que supere la 6\u00ba carta de terreno.<\/strong><\/p>\n<p>No resulta dif\u00edcil que el juego te lleve a pensar es esas partidas de Gorka Morka contra el KRG y sus \u201ccacharros\u201d en mitad del desierto, pero sin ning\u00fan conocimiento previo del WH40K, tambi\u00e9n se disfrutar y te sumerge en el universo del juego de GW. <strong>Os invito a probarlo, seguro que no os defraudar\u00e1<\/strong><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-6312 lazyload\" data-src=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-1024x314.jpg\" alt=\"\" width=\"1024\" height=\"314\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-1024x314.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-300x92.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-768x236.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-150x46.jpg 150w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo-500x153.jpg 500w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2018\/05\/Imagen-Articulo-Gretchinz-auto-rojo.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/314;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Games Workshop ha apostado por la renovaci\u00f3n, tanto de juegos como de tem\u00e1ticas, tras la publicaci\u00f3n de la 8\u00ba edici\u00f3n. Como parte de&#8230;<\/p>\n","protected":false},"author":5,"featured_media":6306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_965112277219911_1711957949078873":"","twitter_719274304828010500_719274304828010500":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","rating_form_position":"","rating_results_position":"","mr_structured_data_type":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-6260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos"],"aioseo_notices":[],"multi-rating":{"mr_rating_results":[{"adjusted_star_result":0,"star_result":0,"total_max_option_value":5,"adjusted_score_result":0,"score_result":0,"percentage_result":0,"adjusted_percentage_result":0,"count":0,"post_id":6260}]},"_links":{"self":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/6260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/comments?post=6260"}],"version-history":[{"count":19,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/6260\/revisions"}],"predecessor-version":[{"id":17001,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/6260\/revisions\/17001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/media\/6306"}],"wp:attachment":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/media?parent=6260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/categories?post=6260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/tags?post=6260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}