{"id":890,"date":"2016-06-13T08:46:27","date_gmt":"2016-06-13T06:46:27","guid":{"rendered":"http:\/\/www.elcornetin.es\/blog\/?p=890"},"modified":"2022-04-02T12:55:19","modified_gmt":"2022-04-02T10:55:19","slug":"entrevista-cosplayer-benihime","status":"publish","type":"post","link":"https:\/\/www.elcornetin.es\/blog\/entrevista\/entrevista-cosplayer-benihime\/","title":{"rendered":"[Entrevista] Cosplayer Benihime."},"content":{"rendered":"<p>El <strong>cosplay\u00a0<\/strong> <i>(<span class=\"t_nihongo_kanji\" lang=\"ja\" xml:lang=\"ja\">\u30b3\u30b9\u30d7\u30ec<\/span> <span class=\"t_nihongo_romaji\"><i>kosupure<\/i><\/span>)<\/i> tiene un enfoque cultural espec\u00edfico dedicado a la representaci\u00f3n realista de una idea o un personaje propio de la ficci\u00f3n.\u00a0\u00a0La <strong>primera aparici\u00f3n<\/strong> de la palabra <i>kosupure<\/i> (aunque el t\u00e9rmino es una contracci\u00f3n de <i><b>costume play<\/b><\/i>, juego de disfraz) fue en un n\u00famero de la revista <strong><i>My Anime<\/i> <\/strong>en<strong> 1983<\/strong>.<\/p>\n<p>Lo cierto es que en la Redacci\u00f3n sabemos muy poco de <em>Cosplay<\/em>. Si podemos dar nuestra opini\u00f3n sobre cu\u00e1l nos gusta m\u00e1s o cu\u00e1l est\u00e1 m\u00e1s conseguido pero, la verdad, no tenemos ni idea.<\/p>\n<p>Y en esto est\u00e1bamos cuando mi m\u00f3vil vibr\u00f3 y en la pantalla apareci\u00f3: \u00ab<strong>Benihine<\/strong>: Sr. K, \u00bfunos tacos esta tarde?\u00bb<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_895\" aria-describedby=\"caption-attachment-895\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-895 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4-300x212.jpg\" alt=\"b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4\" width=\"300\" height=\"212\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4-300x212.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4-768x543.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4-1024x724.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/b698ce4a-6b6a-4e34-9d22-2783d6ac8ca4.jpg 1172w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/212;\" \/><\/a><figcaption id=\"caption-attachment-895\" class=\"wp-caption-text\"><em>Por favor, \u00a1identif\u00edquese! \u00a1Benihime Multipase!<\/em><\/figcaption><\/figure>\n<p><strong>Nombre:<\/strong> Berta Z<\/p>\n<p><strong>Alias:<\/strong> Benihime<\/p>\n<p><strong>Twitter:\u00a0<\/strong><a href=\"https:\/\/twitter.com\/Benihime_Chan\" target=\"_blank\" rel=\"noopener\">@Benihime_Chan<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_912\" aria-describedby=\"caption-attachment-912\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-912 size-large lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04-1024x717.jpg\" alt=\"04\" width=\"1024\" height=\"717\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04-1024x717.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04-300x210.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04-768x538.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/04.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/717;\" \/><\/a><figcaption id=\"caption-attachment-912\" class=\"wp-caption-text\"><em>Ya estoy lista para la entrevista<\/em><\/figcaption><\/figure>\n<p><strong>K<\/strong> &#8211; \u00bfQu\u00e9 es el Cosplay?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211; Cosplay viene de la palabra <strong>Costume y Play<\/strong>. Te disfrazas de tu\u00a0personaje favorito, ya sea manga, videojuegos y lo interpretas. Generalmente lo haces\u00a0por hobby, intentas posar chulamente en las fotos cuando te las piden en eventos&#8230; La\u00a0definici\u00f3n de Cosplay ser\u00eda esa, aunque<strong> para m\u00ed<\/strong>, la definici\u00f3n es<strong> hobby y diversi\u00f3n<\/strong>.<\/p>\n<p><strong>K<\/strong> &#8211;\u00a0\u00bfC\u00f3mo lo conociste? \u00bfCu\u00e1les fueron tus primeros pasos?:<\/p>\n<figure id=\"attachment_900\" aria-describedby=\"caption-attachment-900\" style=\"width: 240px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-900 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851-240x300.jpg\" alt=\"IMG_3851\" width=\"240\" height=\"300\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851-240x300.jpg 240w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851-768x960.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851-819x1024.jpg 819w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3851.jpg 1379w\" data-sizes=\"(max-width: 240px) 100vw, 240px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 240px; --smush-placeholder-aspect-ratio: 240\/300;\" \/><\/a><figcaption id=\"caption-attachment-900\" class=\"wp-caption-text\"><em>Chobits \u00bfviejuna?<\/em><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211; La primera vez que pis\u00e9 un Sal\u00f3n del Manga ten\u00eda <strong>14 a\u00f1os<\/strong> (hace 12 a\u00f1os, me siento viejuna) y me enamor\u00e9 de un\u00a0grupal que vi de Naruto, donde estaban TODOS. Tambi\u00e9n cabe decir que yo ni siquiera\u00a0hab\u00eda visto Naruto en mi vida, pero supe que quer\u00eda hacerlo. Pero no fue hasta los <strong>16\u00a0a\u00f1os<\/strong> que me anim\u00e9 a ello con un <strong>traje de Chuck Norris<\/strong> (que en aquella \u00e9poca era lo\u00a0suyo). Fue horriblemente cutre, pero me divert\u00ed un mont\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>K<\/strong> &#8211; Imag\u00ednate en un trabajo de oficina con gente normal. Un compa\u00f1ero te dice: \u201dMi hija me\u00a0ha dicho: Mam\u00e1, quiero ser <em>cosplayer<\/em>\u201d. \u00bfQu\u00e9 le dirias?:<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211; Ya se ha dado un caso parecido,\u00a0trabajo en una oficina y mi compa\u00f1era de trabajo me dijo: \u00abMi hermana peque\u00f1a quiere\u00a0ser <em>Cosplayer<\/em>\u00bb\u00a0\u00bfQu\u00e9 decir? La dije que si necesitaba ayuda, que contase conmigo.<\/p>\n<p><strong>K<\/strong> &#8211; Resume como es el <strong>paso a paso<\/strong> de un <em>Cosplay<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211; Bueno. Esto es como todo. Ves algo que\u00a0te gusta y con lo que te sientes identificado y ya lo maquinas en tu mente. Los\u00a0accesorios, los patrones de tela o armadura&#8230;) Es un proceso lento, porque le pones\u00a0mimo a todo, desde la tela que quiz\u00e1s cubra tus botas hasta el maquillaje que te\u00a0caracteriza.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong>\u00a0\u00bfQu\u00e9 es lo que hace <strong>excelente<\/strong> un <em>cosplay<\/em>?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211; Para esa no hay una respuesta exacta,\u00a0porque para gustos los colores. Algunos dir\u00edan que <strong>el trabajo<\/strong> en \u00e9l, otros dir\u00edan que la\u00a0<strong>caracterizaci\u00f3n<\/strong>, otros el <strong>parecido<\/strong>&#8230; En mi caso lo que mas me gusta es<strong> la interpretaci\u00f3n<\/strong>\u00a0en fotos y videos y el parecido.<\/p>\n<p style=\"text-align: justify;\"><strong>K<\/strong> &#8211;\u00a0Hace tiempo vi que en <strong>EEUU<\/strong> hab\u00eda como <strong>grupos<\/strong> que se reunian para preparar los\u00a0cosplays e ir a las convenciones. \u00bfHay algo as\u00ed en <strong>Espa\u00f1a<\/strong>?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> &#8211;\u00a0Hay varios foros de ello\u00a0donde la gente se junta para hacer grupales, pedir ayuda, etc. Supongo que el m\u00e1s\u00a0famoso es <em>Foro Cosplay<\/em> de Facebook.<\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_4335.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-902 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_4335-225x300.jpg\" alt=\"IMG_4335\" width=\"225\" height=\"300\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_4335-225x300.jpg 225w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_4335.jpg 750w\" data-sizes=\"(max-width: 225px) 100vw, 225px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;\" \/><\/a>K &#8211;<\/strong>\u00a0En general se ve que las <em>cosplayers<\/em> se \u201cvisten\u201d con <em>cosplays<\/em> de diferentes tem\u00e1ticas: c\u00f3mics, manga, juegos, etc. \u00bfConoc\u00e9is el cosplay que vest\u00eds al dedillo o veis un personaje\u00a0os gusta e investig\u00e1is sobre \u00e9l?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Hay de todo. Yo generalmente <strong>me visto de algo que me\u00a0gusta<\/strong> porque lo he visto en anime, o he jugado a ello (Algo de lo que podr\u00eda decirse que\u00a0me considero forofa). Pero <strong>hay excepciones<\/strong>. Mi cosplay de <strong>Elektra<\/strong> b\u00e1sicamente<strong> me lo\u00a0pidieron para un evento<\/strong>, pero yo <strong>no ten\u00eda ni idea<\/strong> de ella. <strong>Decid\u00ed informarme<\/strong> y leer sobre\u00a0el asunto y ahora <strong>soy una fan incondicional de ella<\/strong> y Daredevil.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong> \u00bfCu\u00e1l es el<strong> elemento m\u00e1s raro<\/strong> que ha usado para un cosplay?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> En el cosplay TODO es\u00a0raro. Yo he ido con cosplayers por la calle y replantearnos <strong>coger cart\u00f3n de los\u00a0contenedores<\/strong> solo \u00abPOR SI ACASO\u00bb. Hasta ahora he usado lo mas b\u00e1sico, pero se de una\u00a0cosplayer,\u00a0<a href=\"https:\/\/twitter.com\/museumluzbel\" target=\"_blank\" rel=\"noopener\">Luzbel<\/a>, que se hizo una armadura con<strong> chapas de latas<\/strong>.<\/p>\n<p><strong>K &#8211;<\/strong>\u00a0\u00bfCu\u00e1nto <strong>tiempo<\/strong> de media se dedica a un cosplay?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime<\/strong> <strong>&#8211;<\/strong> Depende de la dificultad. Puedo\u00a0poner varios ejemplos. Mi cosplay de Selphie que se trata de un vestidito muy sencillo,\u00a0tard\u00e9 <strong>una tarde<\/strong>. Luego hay cosplays mas elaborados que requieren tiempo debido a las\u00a0<em>props<\/em> (Detalles que no son tela) Por ejemplo Mikasa de Ataque a los titanes lleva un\u00a0equipo en sus caderas y unas espadas que llevaron <strong>meses de preparaci\u00f3n<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong> \u00bfCu\u00e1l es <strong>el que m\u00e1s te ha costado<\/strong> hacer?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Elizabeth de Bioshock, pero por una sencilla\u00a0raz\u00f3n: HOMBRERAS. no hab\u00eda puesto hombreras en mi vida y decid\u00ed forrar la chaqueta\u00a0en vez de hacerla con tela sin m\u00e1s. Era mi primera vez. FUE HORRIBLE. Pero ahora se\u00a0que si tengo que hacer algo igual o parecido, lo har\u00eda a la primera.<\/p>\n<figure id=\"attachment_905\" aria-describedby=\"caption-attachment-905\" style=\"width: 200px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-905 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196-200x300.jpg\" alt=\"IMG_3196\" width=\"200\" height=\"300\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196-200x300.jpg 200w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196-768x1150.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196-684x1024.jpg 684w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/IMG_3196.jpg 1368w\" data-sizes=\"(max-width: 200px) 100vw, 200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/300;\" \/><\/a><figcaption id=\"caption-attachment-905\" class=\"wp-caption-text\"><em>Elizabeth de Bioshock<\/em><\/figcaption><\/figure>\n<p><strong>K &#8211;<\/strong> \u00bfCu\u00e1l es <strong>el que menos te ha costado hacer<\/strong>?:<\/p>\n<p><strong>Benihime &#8211;<\/strong> Jawas, Star Wars. Lo hice con mi amiga <a href=\"https:\/\/twitter.com\/DannyBocabit\" target=\"_blank\" rel=\"noopener\">Danny Bocabit<\/a>.\u00a0Tardamos 2 tardes y porque est\u00e1bamos perezosas. Pero lo hicimos con grapas y qued\u00f3\u00a0super genial.<\/p>\n<p style=\"text-align: justify;\"><strong>K\u00a0&#8211;<\/strong> Por resultados. \u00bfCu\u00e1l es que m\u00e1s te ha gustado y cu\u00e1l es el que menos?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Hasta el\u00a0momento creo que <strong>el <em>cosplay<\/em> que m\u00e1s me gusta es P\u00edcara<\/strong>. Adem\u00e1s es la primera vez\u00a0que cos\u00eda una peluca (que al final no result\u00f3 ser para tanto) y me encant\u00f3 el resultado.\u00a0<strong>El que menos el de Samus Aran<\/strong>, porque intent\u00e9 hacerlo con tela de charol y las medidas\u00a0no fueron como hubiese deseado que fueran.<\/p>\n<p><strong>K &#8211;<\/strong>\u00a0\u00bfQu\u00e9 <em>cosplay<\/em> quieres hacerte pero lo ves casi imposible? \u00bfPor qu\u00e9?<\/p>\n<p><strong>Benihime &#8211;<\/strong> A d\u00eda de hoy<strong> quiero\u00a0hacerme la armadura de Samus Aran<\/strong>, pero lo veo casi imposible porque requiere\u00a0tiempo y pr\u00e1ctica, y yo soy una persona muy impaciente. Las telas son lo m\u00edo.<\/p>\n<p><strong>K &#8211;<\/strong> \u00bfUn <em>cosplay<\/em> que<strong> nunca te har\u00edas<\/strong>?<\/p>\n<p><strong>Benihime &#8211;<\/strong> Voy a englobar y decir que no me har\u00eda ninguno que\u00a0sea una versi\u00f3n \u00abpersona\u00bb de un<strong> animal o monstruo.<\/strong> Como Pikachu, o Gnar o derivados.\u00a0Me encantan, pero no son mi estilo.<\/p>\n<figure id=\"attachment_908\" aria-describedby=\"caption-attachment-908\" style=\"width: 200px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-908 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567-200x300.jpg\" alt=\"_R3A5567\" width=\"200\" height=\"300\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567-200x300.jpg 200w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567-768x1152.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567-683x1024.jpg 683w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/R3A5567.jpg 1365w\" data-sizes=\"(max-width: 200px) 100vw, 200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/300;\" \/><\/a><figcaption id=\"caption-attachment-908\" class=\"wp-caption-text\"><em>\u00abAhora soy una fan incondicional de Elektra\u00bb<\/em><\/figcaption><\/figure>\n<p><strong>K\u00a0&#8211;<\/strong> Los <em>cosplays<\/em> <strong>usados<\/strong>, \u00bfqu\u00e9 haces con ellos?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Los hay que lo <strong>venden<\/strong> o <strong>reutilizan<\/strong> partes\u00a0para otros cosplays. Yo los tengo todos <strong>guardaditos<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong> \u00bfAlguna <em>cosplayer<\/em> que te guste especialmente? \u00bfPor qu\u00e9?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211; <\/strong>Dos, y espa\u00f1olas adem\u00e1s.<strong> <a href=\"https:\/\/twitter.com\/Elle_Cojplei\" target=\"_blank\" rel=\"noopener\">Elle\u00a0Cosplay<\/a><\/strong> y <strong><a href=\"https:\/\/twitter.com\/ShanoaNebula\" target=\"_blank\" rel=\"noopener\">Nebulaluben Cosplay<\/a><\/strong>. Creo que el panorama espa\u00f1ol tiene artistas geniales\u00a0como ellas. Ambas creo que lo tienen todo. Caracterizaci\u00f3n, ganas y talento. Creo que son de lo mejor que hay.<\/p>\n<p style=\"text-align: justify;\"><strong>K\u00a0&#8211;<\/strong>\u00a0Para iletrados. Cuando vamos a un Sal\u00f3n o Expoc\u00f3mic, \u00bf<strong>en qu\u00e9 debemos fijarnos<\/strong> en los\u00a0cosplays?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime <\/strong> &#8211; No hace falta ser un sabio para que te guste el cosplay o te fijes. Si t\u00fa ves un\u00a0personaje que te gusta y conoces, t\u00fa mismo comprobar\u00e1s si est\u00e1 bien o est\u00e1 mal, o te\u00a0gusta o te deja de gustar. Para gustos los colores.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong>\u00a0<a href=\"https:\/\/twitter.com\/jamieleecurtis\/status\/739973592457191425\/photo\/1?ref_src=twsrc%5Etfw\">Jeami Lee Curtis<\/a> ha acudido a ver Warcraft vestida con un cosplay de chaman orcos.\u00a0\u00bfQu\u00e9 opinas tanto del <em>cosplay<\/em> como de que fuera as\u00ed? \u00bfTe hubiera gustado ser su\u00a0<em>cosmaker<\/em> o compa\u00f1era?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Vi la foto y <strong>me pareci\u00f3 genial<\/strong>. Siempre quise ir de Draka ya\u00a0que soy una fan de Warcraft desde que tengo memoria. Pero no. Ni ser su compa\u00f1era ni\u00a0ser su cosmaker. Ella lo hizo por gusto y porque le apetec\u00eda. Yo no \u00abinterfiero\u00bb en un\u00a0cosplay a no ser que alguien me lo pida expresamente.<\/p>\n<figure id=\"attachment_909\" aria-describedby=\"caption-attachment-909\" style=\"width: 240px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/ABUELITA.png\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-909 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/ABUELITA-240x300.png\" alt=\"ABUELITA\" width=\"240\" height=\"300\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/ABUELITA-240x300.png 240w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/ABUELITA.png 600w\" data-sizes=\"(max-width: 240px) 100vw, 240px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 240px; --smush-placeholder-aspect-ratio: 240\/300;\" \/><\/a><figcaption id=\"caption-attachment-909\" class=\"wp-caption-text\"><em>Propuesta del Cornetin con 55 a\u00f1os<\/em><\/figcaption><\/figure>\n<p><strong>K &#8211;<\/strong> Vamos terminando. Berta ya tiene 55 a\u00f1os. \u00bfTe ver\u00edas con este <em>cosplay<\/em>?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> Por supuesto. Y\u00a0lo bien que te lo pasas y lo agradecido que est\u00e1s cuando te sacan una foto porque les ha\u00a0gustado o les ha hecho gracia&#8230;.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong>\u00a0\u00bfTe animas a hacer un <em>making off<\/em> de tu pr\u00f3ximo cosplays para que publiquemos el paso\u00a0a paso?<\/p>\n<p style=\"text-align: justify;\"><strong>Benihime &#8211;<\/strong> No tendr\u00eda ning\u00fan problema, aunque los siguientes cosplays en mi lista son\u00a0bastante sencillitos (Aeris y 2 de Rinoa) Pero tengo presente hacer el <em>cosplay<\/em> casi\u00a0imposible que he citado antes, el de Samus Aran. Har\u00eda un making off con mis gracias y\u00a0desgracias encantada, para que aprendamos todos juntos.<\/p>\n<p style=\"text-align: justify;\"><strong>K &#8211;<\/strong> En la Redacci\u00f3n tenemos una especie de apuesta.\u00bfCospleyarias a <strong>Juls <\/strong>de<strong> Leeloo Dallas<\/strong>?<\/p>\n<p><strong>Benihime &#8211;<\/strong> Encantada de la vida, pero s\u00f3lo si voy a su lado de Diva Plavalaguna \u2665<\/p>\n<p><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"alignnone wp-image-913 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b-300x206.jpg\" alt=\"05_b\" width=\"300\" height=\"206\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b-300x206.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b-768x528.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b-1024x704.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/05_b.jpg 2048w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/206;\" \/><\/a><a href=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo.jpg\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-910 size-medium lazyload\" data-src=\"http:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo-300x200.jpg\" alt=\"leeloo\" width=\"300\" height=\"200\" data-srcset=\"https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo-300x200.jpg 300w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo-768x512.jpg 768w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo-1024x683.jpg 1024w, https:\/\/www.elcornetin.es\/blog\/wp-content\/uploads\/2016\/06\/leeloo.jpg 2048w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/a><\/p>\n<p>PD: En breve pondremos los autores de las fotos de las sesiones de Benihime Chan. Disculpad las molestias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cosplay\u00a0 (\u30b3\u30b9\u30d7\u30ec kosupure) tiene un enfoque cultural espec\u00edfico dedicado a la representaci\u00f3n realista de una idea o un personaje propio de la&#8230;<\/p>\n","protected":false},"author":5,"featured_media":893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"facebook_965112277219911_1711957949078873":"","twitter_719274304828010500_719274304828010500":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","rating_form_position":"","rating_results_position":"","mr_structured_data_type":"","footnotes":""},"categories":[2921],"tags":[],"class_list":["post-890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista"],"aioseo_notices":[],"multi-rating":{"mr_rating_results":[{"adjusted_star_result":0,"star_result":0,"total_max_option_value":5,"adjusted_score_result":0,"score_result":0,"percentage_result":0,"adjusted_percentage_result":0,"count":0,"post_id":890}]},"_links":{"self":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":27,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":16835,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/posts\/890\/revisions\/16835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/media\/893"}],"wp:attachment":[{"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elcornetin.es\/blog\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}